{"id":970,"date":"2021-01-22T16:45:51","date_gmt":"2021-01-22T16:45:51","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=970"},"modified":"2021-01-26T13:40:39","modified_gmt":"2021-01-26T13:40:39","slug":"nuestro-proyecto-es-trabajar-mas-en-lo-social","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/01\/22\/nuestro-proyecto-es-trabajar-mas-en-lo-social\/","title":{"rendered":"NUESTRO PROYECTO ES TRABAJAR MAS EN LO SOCIAL"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"970\" class=\"elementor elementor-970\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3efe1ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3efe1ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59880fbc\" data-id=\"59880fbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45d47fb7 elementor-widget elementor-widget-text-editor\" data-id=\"45d47fb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"672\" height=\"673\" class=\"wp-image-972\" src=\"http:\/\/www.elpolitologoyelpolitico.com.ar:8081\/wordpress\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-21-at-9.02.49-PM-edited.jpeg\" alt=\"\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-21-at-9.02.49-PM-edited.jpeg 672w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-21-at-9.02.49-PM-edited-300x300.jpeg 300w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-21-at-9.02.49-PM-edited-150x150.jpeg 150w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/><\/figure>\n\n<p>Diego Rosati, Naci\u00f3 en Viedma y desde muy chico se dedic\u00f3 a la actividad deportiva. A los 5 a\u00f1os comenz\u00f3 yudo y termin\u00f3 su carrera a los 33 a\u00f1os. Logr\u00f3 una excelente participaci\u00f3n a nivel Local, Regional, Nacional e Internacional. Despu\u00e9s de la \u00faltima competici\u00f3n en los juegos Ol\u00edmpicos de Londres (2012) volvi\u00f3 a Viedma, luego de estar 18 a\u00f1os viviendo en Buenos Aires.<\/p>\n\n<p>Empez\u00f3 a trabajar en la Secretar\u00eda de Deportes, en la parte interna, teniendo total conocimiento de los programas que exist\u00edan en esa \u00e1rea y cuando la Gobernadora Arabela Carreras asumi\u00f3, le propuso el cargo de Secretario de Deporte.<\/p>\n\n<p>La Secretar\u00eda de Deportes, depende del Ministerio de Turismo, Cultura y Deporte de la Provincia de R\u00edo Negro a cargo de la Ministra Martha V\u00e9lez y se est\u00e1 trabajando en equipo, logrando cierta articulaci\u00f3n con respecto a las pol\u00edticas p\u00fablicas que se gestionan e implementan en lo deportivo.<\/p>\n\n<p>Existe una relaci\u00f3n muy buena con la Gobernadora y hay que recordar que Arabela cumpli\u00f3 un rol importante en el Ministerio de Turismo y Deporte, logrando cierto conocimiento, lo cual permite una mejor gobernabilidad.<\/p>\n\n<p>Seg\u00fan Rosati: <strong><em>\u201cDentro de la Secretar\u00eda armamos un equipo muy t\u00e9cnico en el Deporte y nos hicimos fuertes para poder tener una excelente gesti\u00f3n\u201d.<\/em><\/strong><\/p>\n\n<p>La Provincia de R\u00edo Negro siempre est\u00e1 entre los mejores de la competencia y posiciona a los rionegrinos en los primeros lugares del deporte argentino Nacional. \u00a0<\/p>\n\n<p>Se empez\u00f3 a ver al deporte como una herramienta que pod\u00eda mejorar la calidad de vida de los rionegrinos, m\u00e1s all\u00e1 de la competencia, integrando a los adultos mayores, los chicos con discapacidad, fortaleciendo la igualdad de g\u00e9nero, la inclusi\u00f3n social y apuntando a una actividad f\u00edsica saludable para las personas.<\/p>\n\n<p><strong><em>\u201cNuestro proyecto es trabajar m\u00e1s en lo social, desde la L\u00ednea Sur, pasando por el Alto Valle, Valle Medio, Zona Atl\u00e1ntica y todo el territorio rionegrino, para un deporte m\u00e1s Federal, m\u00e1s territorial\u201d <\/em><\/strong>expres\u00f3 el Secretario de Deporte.<\/p>\n\n<p>En estos momentos, se est\u00e1 trabajando con profesores en los parajes rurales y en las comisiones de fomento para asistir a personas e integrarlas a la actividad deportiva, teniendo la posibilidad de que sean los futuros representantes para los juegos ol\u00edmpicos, ense\u00f1\u00e1ndoles deportes individuales como por ejemplo un lanzamiento de atletismo.<\/p>\n\n<p>En esta Provincia, existen varias personas que se pueden comprometer con el deporte, entrenando para llegar a competir a distintos juegos Nacionales e Internacionales.<\/p>\n\n<p>Para Diego Rosati; <strong><em>\u201cel objetivo de esta Gesti\u00f3n es que los chicos entiendan y conozcan el mundo del deporte\u201d.<\/em><\/strong><\/p>\n\n<p>En la actividad deportiva, se necesita el contacto a contacto entre los participantes y existen diversos programas en la Provincia que por el momento no se pueden concretar de manera presencial, pero se traslad\u00f3 a lo virtual. Se realizaron los juegos rionegrinos de atletismo y los juegos adaptado para chicos con discapacidad de forma virtual. Fue un \u00e9xito, y un mont\u00f3n de gente se sum\u00f3.<\/p>\n\n<p>Durante el 2020, se apunt\u00f3 a capacitar a varias personas y a estructurarse para que los clubes logren generar nuevas pol\u00edticas internas de autogesti\u00f3n. Es por eso, que se lanz\u00f3 una capacitaci\u00f3n muy grande en cuanto a \u201cautogesti\u00f3n deportiva\u201d y \u201cmanagement deportivo\u201d con 4800 inscriptos, y esa capacitaci\u00f3n estuvo acompa\u00f1ada con un aporte econ\u00f3mico a los clubes que se lanz\u00f3 en el programa \u201cMAS DEPORTE\u201d, en donde se distribuy\u00f3 m\u00e1s de $15.000.000 para asistir a los clubes que m\u00e1s lo necesitaban.<\/p>\n\n<p>En cuanto a lo virtual, se arm\u00f3 el \u00e1rea de capacitaci\u00f3n con Silvia Paniagua en Cincos Saltos y el Director de eventos deportivos Caupolican Rodr\u00edguez en Bariloche, y se realizaron 53 capacitaciones en distintas tem\u00e1ticas deportivas, en cuanto a t\u00e9cnicas de atletismo, futbol, futbol playa, y otras capacitaciones referidas a igualdad de g\u00e9nero, derechos en el deporte, con la asistencia de m\u00e1s de 5000 personas y en un t\u00e9rmino de 6 meses se lleg\u00f3 a 10.000 personas que se capacitaron en esta \u00e1rea.<\/p>\n\n<p>Diego Rosati sostuvo que <strong><em>\u201cEl deporte me dio la posibilidad de expresarme y mostrar lo que yo pod\u00eda dar en el combate\u201d. \u201cUno crea y forma su propia t\u00e9cnica, aprende la base que le ense\u00f1a cada profesor y el deporte me dio la posibilidad hermosa de conocer el mundo.\u201d<\/em><\/strong><\/p>\n\n<p>Desde los 17 a\u00f1os represent\u00f3 a la selecci\u00f3n Argentina en Yudo, viajando a distintos lados, competiendo 20 o 30 veces por a\u00f1o y generando un v\u00ednculo con otras personas con distintas culturas.<\/p>\n\n<p>Cuando comenz\u00f3 la pandemia, se realiz\u00f3 un video desde la Secretar\u00eda de Deportes de R\u00edo Negro, en donde varios actores reconocidos del deporte local, Nacional e Internacional difundieron las medidas que hay que tomar por el Covid 19.<\/p>\n\n<p><strong>\u201cEl deporte te da esa posibilidad de conocer gente de diversos lugares y entablar relaciones sociales y estoy orgulloso de lo que hice\u201d<\/strong> expres\u00f3 el actor pol\u00edtico.<\/p>\n\n<p>Rosati afirma que <strong><em>\u201c la pol\u00edtica es una herramienta para transformar la vida de cada uno de los ciudadanos y las pol\u00edticas p\u00fablicas que se generan desde este gobierno siempre apunta a eso\u201d.<\/em><\/strong><\/p>\n\n<p><strong><em>\u201cEs muy importante que dejemos de ver la competencia del deporte, y nos enfoquemos m\u00e1s en lo social, gestionando pol\u00edticas deportivas para mejorar la calidad de vida de cada persona\u201d. <\/em><\/strong>Resalt\u00f3 Rosati.<\/p>\n\n<p>Existen muchas personas que no est\u00e1n en el universo del deporte y desde la Secretar\u00eda se apunta a trabajar con tres grandes ejes;<\/p>\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>Los que ya est\u00e1n compitiendo.<\/strong> Que contin\u00faen con esa intensidad y desde la Secretar\u00eda se seguir\u00e1 asistiendo para que tengan los recursos necesarios para la competencia.<\/li>\n<li><strong>El p\u00fablico medio.<\/strong> \u00a0Que ya est\u00e1n en el \u00e1mbito deportivo y hay que cuidarlos, orientarlos y brindarles nuevas oportunidades para que sigan practicando el deporte.<\/li>\n<li>\u00a0<strong>Los que todav\u00eda no est\u00e1n inmerso en el deporte. <\/strong>Desde la Secretar\u00eda, apuntan a que formen parte del deporte porque es la mejor herramienta para cambiar la calidad de vida.Este p\u00fablico es el gran desaf\u00edo que tiene la Secretaria.<\/li>\n<\/ol>\n\n<p>Se cre\u00f3 una direcci\u00f3n espec\u00edfica de deporte adaptado para chicos con discapacidad a cargo del Prof.\u00a0 Javier Leiria que est\u00e1 realizando varias actividades.<\/p>\n<p><strong><em>\u201cEstamos esperando que las condiciones se den, y l\u00f3gicamente no tenemos la decisi\u00f3n para autorizar o desautorizar una actividad y cada vez que vamos a implementar algo, dialogamos con el Ministerio de Salud que son los que est\u00e1n capacitados para decir que cosas se hacen y que cosas no\u201d<\/em><\/strong> finaliz\u00f3 Rosati.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/01\/22\/nuestro-proyecto-es-trabajar-mas-en-lo-social\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Diego Rosati, Naci\u00f3 en Viedma y desde muy chico se dedic\u00f3 a la actividad deportiva. A los 5 a\u00f1os comenz\u00f3 yudo y termin\u00f3 su carrera a los 33 a\u00f1os. Logr\u00f3 una excelente participaci\u00f3n a nivel Local, Regional, Nacional e Internacional. Despu\u00e9s de la \u00faltima competici\u00f3n en los juegos Ol\u00edmpicos de Londres (2012) volvi\u00f3 a Viedma, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-970","post","type-post","status-publish","format-standard","hentry","category-actores-politicos"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}