{"id":5161,"date":"2021-07-07T01:05:56","date_gmt":"2021-07-07T01:05:56","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=5161"},"modified":"2021-07-07T01:06:47","modified_gmt":"2021-07-07T01:06:47","slug":"en-el-trascurso-del-dia-se-restablecera-el-alumbrado-publico-en-el-barrio-villa-del-carmen","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/07\/en-el-trascurso-del-dia-se-restablecera-el-alumbrado-publico-en-el-barrio-villa-del-carmen\/","title":{"rendered":"EN EL TRASCURSO DEL D\u00cdA SE RESTABLECER\u00c1 EL ALUMBRADO P\u00daBLICO EN EL BARRIO VILLA DEL CARMEN"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5161\" class=\"elementor elementor-5161\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-289bb29a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"289bb29a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2917f56d\" data-id=\"2917f56d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b564c7 elementor-widget elementor-widget-text-editor\" data-id=\"41b564c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>El Departamento de Alumbrado de la Municipalidad de Patagones, informa a la comunidad que en breve se restablecer\u00e1 el alumbrado p\u00fablico en un sector del barrio Villa del Carmen.&nbsp;<\/p>\n\n\n\n<p>Actualmente se ejecuta el recambio de un tablero de medici\u00f3n nuevo a ra\u00edz del incendio registrado en la jornada de ayer, en la calle Francisco Arr\u00f3.&nbsp;<\/p>\n\n\n\n<p>Es importante destacar que, dichas\u00a0 tareas son llevadas adelante en conjunto con el Municipio y operarios de la empresa EDES.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34.jpeg\" alt=\"\" data-id=\"5163\" data-full-url=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34.jpeg\" data-link=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?attachment_id=5163\" class=\"wp-image-5163\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34.jpeg 720w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34-225x300.jpeg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34b.jpeg\" alt=\"\" data-id=\"5164\" data-full-url=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34b.jpeg\" data-link=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?attachment_id=5164\" class=\"wp-image-5164\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34b.jpeg 720w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-06-at-19.20.34b-225x300.jpeg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure><\/li><\/ul><\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/07\/en-el-trascurso-del-dia-se-restablecera-el-alumbrado-publico-en-el-barrio-villa-del-carmen\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El Departamento de Alumbrado de la Municipalidad de Patagones, informa a la comunidad que en breve se restablecer\u00e1 el alumbrado p\u00fablico en un sector del barrio Villa del Carmen.&nbsp; Actualmente se ejecuta el recambio de un tablero de medici\u00f3n nuevo a ra\u00edz del incendio registrado en la jornada de ayer, en la calle Francisco Arr\u00f3.&nbsp; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/5161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=5161"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/5161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/5162"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=5161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=5161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=5161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}