{"id":5117,"date":"2021-07-06T15:30:35","date_gmt":"2021-07-06T15:30:35","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=5117"},"modified":"2021-07-06T15:41:17","modified_gmt":"2021-07-06T15:41:17","slug":"comenzo-con-exito-el-ciclo-de-entrevistas-media-hora-saludable-para-jovenes-atletas-rionegrinos","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/06\/comenzo-con-exito-el-ciclo-de-entrevistas-media-hora-saludable-para-jovenes-atletas-rionegrinos\/","title":{"rendered":"Comenz\u00f3 con \u00e9xito el ciclo de entrevistas Media Hora Saludable para j\u00f3venes atletas rionegrinos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5117\" class=\"elementor elementor-5117\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b4f1337 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b4f1337\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a50d369\" data-id=\"1a50d369\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6861e99 elementor-widget elementor-widget-text-editor\" data-id=\"6861e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><strong>El pasado viernes inici\u00f3 el ciclo de charlas deportivas Media Hora Saludable, a trav\u00e9s de la plataforma Instagram con una gran cantidad de usuarios conectados en la entrevista del m\u00e9dico deport\u00f3logo y coordinador del \u00c1rea de Salud Deportiva Pablo Cozzarin.<\/strong>&nbsp;<\/p>\n\n\n\n<p>El encuentro del pr\u00f3ximo viernes incluir\u00e1 a la nutricionista y antropometr\u00edsta especializada en deporte, Gianina Montenegro.&nbsp;<\/p>\n\n\n\n<p>Durante el estreno del ciclo, Cozzar\u00edn habl\u00f3 de su experiencia como m\u00e9dico deport\u00f3logo y su acompa\u00f1amiento en la carrera de distintos atletas. Adem\u00e1s desarroll\u00f3 t\u00e9cnicas de entrenamiento individual y colectivo orientadas a los deportistas desde su formaci\u00f3n hasta los de alto rendimiento.&nbsp;<\/p>\n\n\n\n<p>El ciclo que conduce el Lic. en Actividad F\u00edsica y Deporte Ger\u00f3nimo Mart\u00ednez, prev\u00e9 un cronograma de encuentros con profesionales en nutrici\u00f3n, psicolog\u00eda, kinesiolog\u00eda y educaci\u00f3n f\u00edsica. M\u00e1s adelante tambi\u00e9n se invitar\u00e1 a deportistas destacados para que compartan consejos y cuenten sus experiencias personales.&nbsp;<\/p>\n\n\n\n<p>El objetivo de este programa es que los y las j\u00f3venes deportistas puedan tener informaci\u00f3n de primera mano de profesionales de la salud y que sumen estos datos a su rutina diaria para optimizar su rendimiento deportivo. Los programas en vivo se transmiten todos los viernes a las 19 por el Instagram de R\u00edo Negro Deporte.&nbsp;<\/p>\n\n\n\n<p>En la transmisi\u00f3n en vivo del viernes 9 de julio, estar\u00e1 presente la reconocida Licenciada en Nutrici\u00f3n y Antropometr\u00edsta especializada en deporte Gianina Montenegro, quien hablar\u00e1 de nutrici\u00f3n deportiva, significado de entrenamiento invisible, alimentaci\u00f3n e hidrataci\u00f3n, su experiencia con clubes y los alcances de la antropometr\u00eda.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/06\/comenzo-con-exito-el-ciclo-de-entrevistas-media-hora-saludable-para-jovenes-atletas-rionegrinos\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El pasado viernes inici\u00f3 el ciclo de charlas deportivas Media Hora Saludable, a trav\u00e9s de la plataforma Instagram con una gran cantidad de usuarios conectados en la entrevista del m\u00e9dico deport\u00f3logo y coordinador del \u00c1rea de Salud Deportiva Pablo Cozzarin.&nbsp; El encuentro del pr\u00f3ximo viernes incluir\u00e1 a la nutricionista y antropometr\u00edsta especializada en deporte, Gianina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/5117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=5117"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/5117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/5118"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=5117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=5117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=5117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}