{"id":4956,"date":"2021-07-01T15:51:26","date_gmt":"2021-07-01T15:51:26","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4956"},"modified":"2021-07-01T15:51:28","modified_gmt":"2021-07-01T15:51:28","slug":"trabajo-firmo-convenios-con-camaras-y-sindicatos-de-villa-regina","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/01\/trabajo-firmo-convenios-con-camaras-y-sindicatos-de-villa-regina\/","title":{"rendered":"Trabajo firm\u00f3 convenios con c\u00e1maras y sindicatos de Villa Regina"},"content":{"rendered":"\n<p>El secretario de Estado de Trabajo, Jorge Stopiello, mantuvo importantes reuniones en Villa Regina y firm\u00f3 convenios con sindicatos y c\u00e1maras de comercio y de productores en materia de capacitaci\u00f3n. <\/p>\n\n\n\n<p>Durante un encuentro mantenido este mi\u00e9rcoles en la mencionada ciudad del Alto Valle, Stopiello firm\u00f3 convenios con la C\u00e1mara de Productores, la C\u00e1mara de Comercio y los gremios UATRE, SOEFRYM, STHIMPRA y de Empleados de Comercio. <\/p>\n\n\n\n<p>Un relevamiento previo con estas instituciones permiti\u00f3 establecer la importancia que significa llevar herramientas de conocimiento, que ser\u00e1n dictadas bajo la modalidad de cursos y\/o talleres, seg\u00fan el caso. <\/p>\n\n\n\n<p>Los entendimientos suscriptos en la jornada son en materia de capacitaci\u00f3n en G\u00e9nero, Discapacidad y Trabajo Infantil y estar\u00e1n a cargo de la Subsecretar\u00eda de Capacitaci\u00f3n y Empleo de la cartera laboral. <\/p>\n\n\n\n<p>El Secretario Stopiello se reuni\u00f3 con la legisladora provincial oriunda de esa localidad, Marcela \u00c1vila, con quien dialogaron sobre aspectos vinculados a la producci\u00f3n y el trabajo. <\/p>\n\n\n\n<p>\u201cCon la legisladora \u00c1vila evaluamos la nueva ley de negociaci\u00f3n colectiva en la administraci\u00f3n p\u00fablica provincial y el mercado laboral local\u201d, destac\u00f3 el secretario Stopiello. <\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/07\/01\/trabajo-firmo-convenios-con-camaras-y-sindicatos-de-villa-regina\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El secretario de Estado de Trabajo, Jorge Stopiello, mantuvo importantes reuniones en Villa Regina y firm\u00f3 convenios con sindicatos y c\u00e1maras de comercio y de productores en materia de capacitaci\u00f3n. Durante un encuentro mantenido este mi\u00e9rcoles en la mencionada ciudad del Alto Valle, Stopiello firm\u00f3 convenios con la C\u00e1mara de Productores, la C\u00e1mara de Comercio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4956"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4957"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}