{"id":4717,"date":"2021-06-26T01:04:30","date_gmt":"2021-06-26T01:04:30","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4717"},"modified":"2021-06-26T01:05:05","modified_gmt":"2021-06-26T01:05:05","slug":"covid-19-en-rio-negro-nuevas-medidas-sanitarias-hasta-el-2-de-julio","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/26\/covid-19-en-rio-negro-nuevas-medidas-sanitarias-hasta-el-2-de-julio\/","title":{"rendered":"COVID-19 en R\u00edo Negro: Nuevas medidas sanitarias hasta el 2 de julio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4717\" class=\"elementor elementor-4717\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73e7e4e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73e7e4e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79b742f7\" data-id=\"79b742f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d9c0277 elementor-widget elementor-widget-text-editor\" data-id=\"5d9c0277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><strong>A trav\u00e9s de la Resoluci\u00f3n 4639, el Ministerio de Salud dispuso extender las medidas sanitarias destinadas a contener los contagios de COVID-19 hasta el de 2 julio, inclusive.<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>CIRCULACI\u00d3N<\/strong>&nbsp;<\/p>\n\n\n\n<p>En la totalidad del territorio, la restricci\u00f3n a la circulaci\u00f3n de las personas ser\u00e1 entre las 22 y las 6 del d\u00eda siguiente. Quedar\u00e1n exceptuadas de la medida de restricci\u00f3n a la circulaci\u00f3n nocturna:&nbsp;<\/p>\n\n\n\n<p>&#8211; Las personas incluidas en el Art\u00edculo 20\u00ba del Decreto Nacional N\u00ba 287\/21 (<a href=\"https:\/\/bit.ly\/3o3kzfH\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/3o3kzfH<\/a>)&nbsp;<\/p>\n\n\n\n<p>&#8211; Los trabajadores de farmacias y estaciones de servicio para el expendio de combustibles&nbsp;<\/p>\n\n\n\n<p>&#8211; Las personas que est\u00e9n asistiendo o regresando a sus hogares procedentes de locales gastron\u00f3micos, con comprobante de reserva o consumo, siempre que se encuentren dentro del lapso temporal establecido.&nbsp;<\/p>\n\n\n\n<p>&#8211; Las personas afectadas al desarrollo de las actividades de cines, teatros y salas de espect\u00e1culos de centros culturales y al p\u00fablico asistente. El p\u00fablico asistente deber\u00e1 acreditar su condici\u00f3n con los tickets de acceso al espect\u00e1culo, que deber\u00e1n especificar la sala a la que se asisti\u00f3, el t\u00edtulo de la obra o concierto y artista, el horario de la funci\u00f3n y el n\u00famero de la butaca que ocup\u00f3.&nbsp;<\/p>\n\n\n\n<p>En todos los casos deber\u00e1n portar el \u201cCertificado \u00danico Habilitante para Circulaci\u00f3n &#8211; Emergencia COVID-19\u201d.&nbsp;<\/p>\n\n\n\n<p><strong>ACTIVIDADES SUSPENDIDAS<\/strong>&nbsp;<\/p>\n\n\n\n<p>&#8211; Las reuniones sociales en domicilios particulares, salvo para la asistencia de personas que requieran especiales cuidados.&nbsp;<\/p>\n\n\n\n<p>&#8211; Las reuniones sociales en espacios p\u00fablicos al aire libre de m\u00e1s de diez personas.&nbsp;<br>&#8211; La realizaci\u00f3n de todo tipo de eventos sociales y recreativos en lugares cerrados que impliquen concurrencia de personas.&nbsp;<\/p>\n\n\n\n<p>&#8211; La actividad de discotecas.&nbsp;<\/p>\n\n\n\n<p>&#8211; La realizaci\u00f3n de eventos, encuentros y competencias deportivas, profesionales o amateurs, que impliquen aglomeraci\u00f3n de personas, en espacios p\u00fablicos o privados, sean estos cerrados o al aire libre. Queda autorizada la realizaci\u00f3n de las competencias oficiales \u201cTorneo Federal A\u201d de f\u00fatbol y \u201cLiga Argentina de B\u00e1squet\u201d, de acuerdo a los protocolos aprobados por las autoridades sanitarias nacionales o provinciales, sin asistencia de p\u00fablico.&nbsp;<\/p>\n\n\n\n<p><strong>HABILITACIONES ESPECIALES<\/strong>&nbsp;<\/p>\n\n\n\n<p>&#8211; Los locales gastron\u00f3micos (restaurantes, bares, etc.) podr\u00e1n funcionar hasta las 24, con un m\u00e1ximo 50% del aforo en relaci\u00f3n con la capacidad m\u00e1xima habilitada, con adecuada y constante ventilaci\u00f3n y con estricta sujeci\u00f3n a los protocolos aprobados. Los propietarios, empleados y aquellos clientes que se encontraren en esos establecimientos a la hora de cierre dispuesta, dispondr\u00e1n de hasta 60 minutos adicionales para retirarse de los mismos y llegar a sus domicilios de residencia dentro de ese lapso, debiendo acreditar tal circunstancia mediante comprobante de consumo o similar. Deber\u00e1 priorizarse la utilizaci\u00f3n de espacios al aire libre, instando en este sentido a las autoridades municipales a facilitar la utilizaci\u00f3n de espacios p\u00fablicos al aire libre.&nbsp;<\/p>\n\n\n\n<p>&#8211; Los locales comerciales de cualquier rubro podr\u00e1n funcionar respetando el horario de circulaci\u00f3n habilitado.&nbsp;<\/p>\n\n\n\n<p>&#8211; Las farmacias y estaciones de servicio -\u00fanicamente para el expendio de combustibles- podr\u00e1n funcionar durante las 24 horas.&nbsp;<\/p>\n\n\n\n<p>&#8211; La realizaci\u00f3n actos p\u00fablicos, protocolares, aniversarios y fiestas populares.&nbsp;<\/p>\n\n\n\n<p>&#8211; La pr\u00e1ctica deportiva en espacios p\u00fablicos y privados cerrados con el 50% del aforo.&nbsp;<\/p>\n\n\n\n<p>&#8211; La actividad deportiva en espacios p\u00fablicos o privados al aire libre, en grupos de hasta diez personas, sin asistencia de p\u00fablico.&nbsp;<br>&#8211; La realizaci\u00f3n de eventos religiosos en lugares cerrados que impliquen concurrencia de personas, en los que deber\u00e1 observarse, como m\u00e1ximo, un 30% de aforo.&nbsp;<\/p>\n\n\n\n<p>&#8211; Las clases presenciales y ensayos de actividades art\u00edsticas, individuales o en grupos reducidos de hasta diez personas con sistema de \u201cburbujas\u201d, seg\u00fan protocolo y con un aforo m\u00e1ximo del 30% del espacio donde se realizan.&nbsp;<\/p>\n\n\n\n<p>&#8211; La apertura de bibliotecas con entrega de libros en puerta, con protocolo vigente, sin ingreso del p\u00fablico al interior de la instituci\u00f3n. No se habilitan las salas de lectura de las bibliotecas.&nbsp;<\/p>\n\n\n\n<p>&#8211; La realizaci\u00f3n de actividades en cines, teatros y salas de espect\u00e1culos de centros culturales a los efectos del desarrollo de artes esc\u00e9nicas, con y sin asistencia de espectadores. En las salas de teatros y de espect\u00e1culos se permite un 50% de aforo, sin expendio de bebidas y comidas y en los cines se permite un 30% de aforo, con expendio de golosinas y bebidas.&nbsp;<\/p>\n\n\n\n<p>&#8211; La actividad de casinos y bingos, durante el horario de circulaci\u00f3n permitido, con un aforo m\u00e1ximo del 50% del espacio disponible.&nbsp;<\/p>\n\n\n\n<p>En todos los casos deber\u00e1 garantizarse el cumplimiento de las Reglas de Conducta Generales y Obligatorias dispuestas en el art\u00edculo 4\u00b0 del Decreto N\u00b0 287\/21 y de los protocolos vigentes.&nbsp;<\/p>\n\n\n\n<p>CLASES Y ACTIVIDADES ESCOLARES&nbsp;<\/p>\n\n\n\n<p>Se prorroga la habilitaci\u00f3n, en todo el territorio de la provincia a excepci\u00f3n del Departamento General Roca, del dictado de clases presenciales y de las actividades educativas no escolares presenciales correspondientes a todos los niveles y modalidades, en la forma que disponga el Ministerio de Educaci\u00f3n y Derechos Humanos.&nbsp;<\/p>\n\n\n\n<p>Se prorroga la habilitaci\u00f3n, en el \u00e1mbito de los Municipios y Comisiones de Fomento localizados dentro del Departamento General Roca, para el dictado de clases presenciales y actividades educativas no escolares presenciales \u00fanicamente en los niveles inicial, primario y educaci\u00f3n especial, en la forma que disponga el Ministerio de Educaci\u00f3n y Derechos Humanos.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/26\/covid-19-en-rio-negro-nuevas-medidas-sanitarias-hasta-el-2-de-julio\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la Resoluci\u00f3n 4639, el Ministerio de Salud dispuso extender las medidas sanitarias destinadas a contener los contagios de COVID-19 hasta el de 2 julio, inclusive.&nbsp; CIRCULACI\u00d3N&nbsp; En la totalidad del territorio, la restricci\u00f3n a la circulaci\u00f3n de las personas ser\u00e1 entre las 22 y las 6 del d\u00eda siguiente. Quedar\u00e1n exceptuadas de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4717"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4718"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}