{"id":4616,"date":"2021-06-24T01:07:28","date_gmt":"2021-06-24T01:07:28","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4616"},"modified":"2021-06-24T01:07:52","modified_gmt":"2021-06-24T01:07:52","slug":"comienza-el-taller-virtual-de-narrativa-japonesa-sado","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/24\/comienza-el-taller-virtual-de-narrativa-japonesa-sado\/","title":{"rendered":"Comienza el taller virtual de narrativa japonesa SAD\u00d6"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4616\" class=\"elementor elementor-4616\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1be07c5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1be07c5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5859e8dd\" data-id=\"5859e8dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bc272c elementor-widget elementor-widget-text-editor\" data-id=\"44bc272c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><strong>El gobierno de Viedma a trav\u00e9s de la Editorial Municipal, comienza su ciclo de capacitaci\u00f3n y formaci\u00f3n para autores y p\u00fablico en general, en esta oportunidad se abre la inscripci\u00f3n al taller de narrativa japonesa SAD\u00d6<\/strong>&nbsp;<\/p>\n\n\n\n<p>La capacitaci\u00f3n ser\u00e1 con cupo limitado y estar\u00e1 a cargo de la tallerista y escritora Susana Franzese destinada a j\u00f3venes y adultos a partir de los 16 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p>Los encuentros ser\u00e1n los s\u00e1bados 10, 17 y 24 de julio a las 16hs. Para informes e inscripciones quienes deseen participar deber\u00e1n comunicarse al mail editorial@viedma.gov.ar\u202f&nbsp;<\/p>\n\n\n\n<p>El taller se llevar\u00e1 adelante mediante tres encuentros virtuales, luego se realizar\u00e1 un trabajo en plataforma virtual donde los participantes tendr\u00e1n a disposici\u00f3n el material de lectura y espacios de foro para intercambio y consultas.&nbsp;<\/p>\n\n\n\n<p><strong>\u201cEl camino del t\u00e9\u201d y el origen hacia la narrativa japonesa<\/strong>&nbsp;<\/p>\n\n\n\n<p>El denominado \u201ccamino del t\u00e9\u201d que da nombre a este taller tiene cuatro principios fundamentales que permiten arribar de manera correcta a la apreciada \u201cceremonia del t\u00e9\u201d, armon\u00eda (wa) respeto (kei) pureza (sei) y tranquilidad (jaku). Estos principios rigen de una experiencia nacida en el siglo XVI que se fue fortaleciendo hasta nuestros d\u00edas y est\u00e1 concebida desde lo comunitario. No hay camino del t\u00e9 en soledad. Partiendo de esta idea, se propone una experiencia de lectura y escritura comunitaria, en donde el intercambio con los otros nutre la propia experimentaci\u00f3n y el descubrimiento personal.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/24\/comienza-el-taller-virtual-de-narrativa-japonesa-sado\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El gobierno de Viedma a trav\u00e9s de la Editorial Municipal, comienza su ciclo de capacitaci\u00f3n y formaci\u00f3n para autores y p\u00fablico en general, en esta oportunidad se abre la inscripci\u00f3n al taller de narrativa japonesa SAD\u00d6&nbsp; La capacitaci\u00f3n ser\u00e1 con cupo limitado y estar\u00e1 a cargo de la tallerista y escritora Susana Franzese destinada a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4616"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4617"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}