{"id":4541,"date":"2021-06-22T22:18:54","date_gmt":"2021-06-22T22:18:54","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4541"},"modified":"2021-06-22T22:18:56","modified_gmt":"2021-06-22T22:18:56","slug":"este-domingo-llega-la-fragata-libertad-a-las-costas-del-balneario-el-condor","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/22\/este-domingo-llega-la-fragata-libertad-a-las-costas-del-balneario-el-condor\/","title":{"rendered":"Este domingo llega la Fragata Libertad a las costas del balneario El C\u00f3ndor"},"content":{"rendered":"\n<p>El pr\u00f3ximo domingo 27 de junio, el buque escuela Fragata \u201cARA\u201d Libertad llegar\u00e1 a las costas del balneario El C\u00f3ndor, donde rendir\u00e1 homenaje a los ca\u00eddos en Malvinas frente al Memorial ubicado en la villa mar\u00edtima. Este emblem\u00e1tico buque llegar\u00e1 alrededor de las 8.30hs, y podr\u00e1 verse desde la costa de El C\u00f3ndor y tambi\u00e9n en la zona de acantilados. <\/p>\n\n\n\n<p>El gobierno de Viedma, recuerda a vecinos y vecinas de la Comarca, que quienes deseen presenciar y disfrutar de esta visita, deber\u00e1n respetar y garantizar las medidas sanitarias de distanciamiento para el cuidado de todas y todos. Ese d\u00eda, el acceso al balneario no tendr\u00e1 restricciones.  <\/p>\n\n\n\n<p>LA RUTA DE NAVEGACI\u00d3N Este a\u00f1o realizar\u00e1 un nuevo viaje de instrucci\u00f3n y tendr\u00e1 como objetivo completar la formaci\u00f3n profesional de los Guardiamarinas en Comisi\u00f3n de la Promoci\u00f3n 149, 84 de Infanter\u00eda de Marina y 105 del Cuerpo Profesional Escalaf\u00f3n Intendencia. Como parte de la preparaci\u00f3n previa al viaje de instrucci\u00f3n, el Buque Escuela zarp\u00f3 del puerto de la Ciudad de Buenos Aires en horas del mediod\u00eda del 18 de junio, para realizar una navegaci\u00f3n de Prueba de M\u00e1quinas, Ajuste de Roles y Adiestramiento. <\/p>\n\n\n\n<p>Esta prueba, es una oportunidad propicia para que los Guardiamarinas en Comisi\u00f3n comiencen con sus pr\u00e1cticas profesionales intensivas supervisadas, comenzando de esta forma la \u00faltima etapa de su formaci\u00f3n acad\u00e9mica que completar\u00e1 su formaci\u00f3n profesional y n\u00e1utica.<\/p>\n\n\n\n<p>El d\u00eda mi\u00e9rcoles 23 de junio, frente a las costas de la ciudad de Mar del Plata, la Fragata participar\u00e1 del recibimiento del nuevo Patrullero Oce\u00e1nico A.R.A. \u201cPIEDRABUENA\u201d para luego continuar su traves\u00eda recorriendo parte del extenso litoral mar\u00edtimo argentino, navegando y fondeando frente a las costas de las ciudades de Viedma, Puerto Madryn y Comodoro Rivadavia.  <\/p>\n\n\n\n<p>FRAGATA ARA LIBERTAD El buque escuela Fragata Libertad tiene como misi\u00f3n completar la formaci\u00f3n profesional de los guardamarinas de la Armada Argentina, contribuyendo al incremento de sus conocimientos mar\u00edtimos e integr\u00e1ndolos a la vida en el mar. Asimismo, contribuye la pol\u00edtica exterior representando a la Rep\u00fablica Argentina en los puertos en los que recala, donde difunde la realidad geogr\u00e1fica, cultural y productiva del pa\u00eds. <\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/22\/este-domingo-llega-la-fragata-libertad-a-las-costas-del-balneario-el-condor\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo domingo 27 de junio, el buque escuela Fragata \u201cARA\u201d Libertad llegar\u00e1 a las costas del balneario El C\u00f3ndor, donde rendir\u00e1 homenaje a los ca\u00eddos en Malvinas frente al Memorial ubicado en la villa mar\u00edtima. Este emblem\u00e1tico buque llegar\u00e1 alrededor de las 8.30hs, y podr\u00e1 verse desde la costa de El C\u00f3ndor y tambi\u00e9n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4541"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4542"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}