{"id":45403,"date":"2026-05-10T23:01:43","date_gmt":"2026-05-11T02:01:43","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=45403"},"modified":"2026-05-10T23:01:44","modified_gmt":"2026-05-11T02:01:44","slug":"giro-dramatico-en-rio-gallegos-hallan-un-cuerpo-descuartizado-e-investigan-si-pertenece-al-jubilado-desaparecido","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2026\/05\/10\/giro-dramatico-en-rio-gallegos-hallan-un-cuerpo-descuartizado-e-investigan-si-pertenece-al-jubilado-desaparecido\/","title":{"rendered":"Giro dram\u00e1tico en R\u00edo Gallegos: hallan un cuerpo descuartizado e investigan si pertenece al jubilado desaparecido"},"content":{"rendered":"\n<p>La b\u00fasqueda de An\u00edbal Cepeda, el jubilado de 72 a\u00f1os que permanec\u00eda desaparecido desde el pasado 20 de abril, dio un vuelco escalofriante este domingo. En el marco de un operativo policial, se hallaron restos humanos descuartizados en un complejo de departamentos ubicado en la zona de la Costanera de la capital santacruce\u00f1a, e intentan determinar si corresponden al hombre buscado.<\/p>\n\n\n\n<p>El operativo se concentr\u00f3 en un predio situado en la intersecci\u00f3n de las calles Gobernador Moyano y Federico Sphur. Se trata de un complejo habitacional que, seg\u00fan fuentes judiciales, integra el listado de bienes decomisados en causas vinculadas a la corrupci\u00f3n p\u00fablica (espec\u00edficamente ligadas al entorno de Daniel Mu\u00f1oz y la causa Vialidad) y que actualmente se encontraba bajo administraci\u00f3n del Estado con custodia de Gendarmer\u00eda Nacional.<\/p>\n\n\n\n<p>Seg\u00fan trascendi\u00f3, el cad\u00e1ver fue encontrado en condiciones atroces: los restos estaban desmembrados y distribuidos en distintos puntos. Mientras que partes del cuerpo fueron localizadas dentro de uno de los departamentos abandonados, las extremidades habr\u00edan sido arrojadas a un pozo ciego en una vivienda colindante.<\/p>\n\n\n\n<p>La investigaci\u00f3n, liderada por la Divisi\u00f3n de Investigaciones (DDI) y Criminal\u00edstica, dio un paso fundamental tras la detenci\u00f3n de Marcelo F\u00e9lix Curtti. El sospechoso fue arrestado en las primeras horas del domingo y su testimonio habr\u00eda aportado informaci\u00f3n crucial para localizar el cuerpo. Curtti se encuentra actualmente imputado como presunto autor de la desaparici\u00f3n y permanece bajo custodia en la Comisar\u00eda Primera.<\/p>\n\n\n\n<p>Previamente, la causa ya hab\u00eda generado sospechas luego de que se detectara el uso de la tarjeta de d\u00e9bito de Cepeda por parte de dos vecinos, lo que activ\u00f3 nuevas l\u00edneas de investigaci\u00f3n sobre el c\u00edrculo cercano y los movimientos del jubilado en sus \u00faltimos d\u00edas.<\/p>\n\n\n\n<p>Aunque todo indica que podr\u00eda tratarse de An\u00edbal Cepeda, las autoridades mantienen la cautela. <strong>\u00abSer\u00eda una locura anticiparnos a confirmar la identidad sin los peritajes correspondientes\u00bb<\/strong>, se\u00f1alaron fuentes de la investigaci\u00f3n.<\/p>\n\n\n\n<p id=\"p-rc_56e56a42c4d2659a-29\">Se espera que en las pr\u00f3ximas horas se realice la autopsia m\u00e9dico-legal y el reconocimiento formal por parte de los familiares para determinar de manera cient\u00edfica la identidad de la v\u00edctima y las causas exactas de la muerte. En el lugar del hallazgo contin\u00faa trabajando personal de Gendarmer\u00eda y peritos judiciales en busca de nuevas pruebas que permitan esclarecer el m\u00f3vil del brutal crimen que conmociona a la provincia de Santa Cruz.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2026\/05\/10\/giro-dramatico-en-rio-gallegos-hallan-un-cuerpo-descuartizado-e-investigan-si-pertenece-al-jubilado-desaparecido\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La b\u00fasqueda de An\u00edbal Cepeda, el jubilado de 72 a\u00f1os que permanec\u00eda desaparecido desde el pasado 20 de abril, dio un vuelco escalofriante este domingo. En el marco de un operativo policial, se hallaron restos humanos descuartizados en un complejo de departamentos ubicado en la zona de la Costanera de la capital santacruce\u00f1a, e intentan [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-45403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/45403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=45403"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/45403\/revisions"}],"predecessor-version":[{"id":45405,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/45403\/revisions\/45405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/45404"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=45403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=45403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=45403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}