{"id":4480,"date":"2021-06-18T22:52:41","date_gmt":"2021-06-18T22:52:41","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4480"},"modified":"2021-06-18T22:53:02","modified_gmt":"2021-06-18T22:53:02","slug":"rio-negro-tendra-ley-de-educacion-ambiental-para-funcionarios-publicos","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/18\/rio-negro-tendra-ley-de-educacion-ambiental-para-funcionarios-publicos\/","title":{"rendered":"R\u00edo Negro tendr\u00e1 ley de educaci\u00f3n ambiental para funcionarios p\u00fablicos."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4480\" class=\"elementor elementor-4480\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fcad034 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fcad034\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-248cd761\" data-id=\"248cd761\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c83c8b elementor-widget elementor-widget-text-editor\" data-id=\"69c83c8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>La Legislatura rionegrina aprob\u00f3 en primera vuelta el proyecto de adhesi\u00f3n a la Ley N\u00ba 27.592, m\u00e1s conocida como \u201cLey Yolanda\u201d.&nbsp;<\/p>\n\n\n\n<p>La iniciativa parlamentaria elaborada por los legisladores del Frente de Todos, Facundo Montecino Odarda y&nbsp; Jos\u00e9 Luis Berros -al que luego se sum\u00f3 la legisladora de Juntos Somos R\u00edo Negro Helena Herrero- establece la capacitaci\u00f3n obligatoria en materia de perspectiva de desarrollo sustentable con especial \u00e9nfasis en cambio clim\u00e1tico, para todos los funcionarios y empleados que integran los tres poderes provinciales.&nbsp;<\/p>\n\n\n\n<p>\u201cEl esp\u00edritu de esta adhesi\u00f3n es concretar una capacitaci\u00f3n espec\u00edfica destinada a quienes integran los diferentes organismos y estamentos del Estado. El objetivo primordial es formalizar la educaci\u00f3n ambiental en todos los funcionarios p\u00fablicos. Es preciso cambiar el paradigma \u2013as\u00ed como lo estamos haciendo en otros \u00e1mbitos- e incorporar de manera definitiva el medio ambiente a las pol\u00edticas p\u00fablicas a trav\u00e9s de la sensibilizaci\u00f3n, la motivaci\u00f3n, la informaci\u00f3n y la capacitaci\u00f3n. Creo que lleg\u00f3 el momento en el que los discursos sobre los beneficios de la sustentabilidad dejen de ser s\u00f3lo conceptos que suenan bien y se transformen de una vez por todas en hechos concretos. El Estado y sus integrantes deben tener grabada a fuego la sustentabilidad en su planificaci\u00f3n y en su accionar diario\u201d, puntualiz\u00f3 Montecino Odarda.&nbsp;<\/p>\n\n\n\n<p>Yolanda Ortiz, fue Doctora en Qu\u00edmica y estuvo al frente de la Secretar\u00eda de Recursos Naturales y Ambiente Humano creada por Juan Domingo Per\u00f3n en los a\u00f1os &#8217;70. Se destac\u00f3 tambi\u00e9n por ser la primera mujer en ejercer un cargo de semejante relevancia en Am\u00e9rica Latina. Su gran innovaci\u00f3n fue incorporar la perspectiva ambiental en la industria, estableciendo sus principios y lineamientos de trabajo a partir de la visi\u00f3n de Per\u00f3n, expresada en lo que se conoce como su \u201cMensaje ambiental a los pueblos y gobiernos del mundo\u201d en el a\u00f1o 1972.&nbsp;<\/p>\n\n\n\n<p>\u201cEl mundo est\u00e1 siendo atravesado por nuevos paradigmas en cuanto a la preservaci\u00f3n clim\u00e1tica, la educaci\u00f3n ambiental resulta completamente necesaria para poner el foco en una gesti\u00f3n racional de los recursos y construir permanentemente actitudes que redunden en beneficio de la naturaleza; incorporando estos valores como horizonte de nuestra sociedad, ecol\u00f3gicamente equilibrada y socialmente sostenible\u201d, finaliz\u00f3 Montecino Odarda.&nbsp;<\/p>\n\n\n\n<p>El 17 de noviembre del a\u00f1o pasado, la C\u00e1mara de Diputados de la Naci\u00f3n sancion\u00f3 la Ley Yolanda. El proyecto -que ya ten\u00eda media sanci\u00f3n del Senado- tiene como objetivo capacitar a quienes integran los diferentes organismos del Estado con el fin de llevar la educaci\u00f3n ambiental a todos los funcionarios p\u00fablicos. Esta normativa de car\u00e1cter integral favorece la toma de las medidas que se consideren necesarias para hacer posible la transversalidad del medio ambiente en las pol\u00edticas p\u00fablicas a trav\u00e9s de la sensibilizaci\u00f3n, motivaci\u00f3n, informaci\u00f3n y capacitaci\u00f3n, incorporando en sus pol\u00edticas y metas la sustentabilidad en su accionar diario.&nbsp;<\/p>\n\n\n\n<p>\u201cTengo muchas esperanzas puestas en esta ley, quienes toman decisiones en todos los poderes deber\u00e1n impulsar pol\u00edticas p\u00fablicas con perspectiva ambiental, lo legisladores, los gobernantes y los jueces que deber\u00e1n fallar con esa mirada\u201d, afirm\u00f3&nbsp;<\/p>\n\n\n\n<p>Destac\u00f3 que \u201ctenemos una provincia hermosa y vasta, con infinidad de recursos naturales pero tambi\u00e9n con una enorme cantidad de problemas ambientales, como la contaminaci\u00f3n del r\u00edo Negro con pesticidas, agroqu\u00edmicos y el fracking; tenemos la crisis h\u00eddrica en Sierra Grande y Jacobacci; en la zona de Las Grutas nuestra gran esperanza tur\u00edstica y de desarrollo tenemos la contaminaci\u00f3n con plomo en San Antonio, la industria de la pesca del langostino con sus desechos; el hierro que vuela en Punta Colorada hacia el mar y las playas; en el Nahuel Huapi en Bariloche hubo que reunir miles de firmas, la miner\u00eda de uranio en plena meseta patag\u00f3nica que se impulsa desde el gobierno provincial en el mismo lugar que proponemos la creaci\u00f3n del \u00c1rea Natural Protegida del Bajo Santa Rosa y Salinas de Trapalc\u00f3 una area natural protegida, entre otros pasivos que deber\u00edan abordarse con con pol\u00edticas p\u00fablicas con perspectiva ambiental\u201d.&nbsp;<\/p>\n\n\n\n<p>Concluy\u00f3 que \u201ctodos deber\u00edamos ponernos de acuerdo, porque las pol\u00edticas ambientales son transversales, no debe haber grieta\u201d.&nbsp;<\/p>\n\n\n\n<p>Por su parte, el legislador Jos\u00e9 Luis Berros critic\u00f3 al gobierno de Mauricio Macri \u201cque permiti\u00f3 la importaci\u00f3n de basura por decreto, que tuvo un secretario de Ambiente que se disfrazaba de pinito o de enredadera, el propio ex presidente defendi\u00f3 las fumigaciones cerca de las escuelas, ojal\u00e1 nuestro gobierno hubiera hecho la ley Yolanda antes del 2015 para que no se digan m\u00e1s burradas en un recinto o en los canales de TV\u201d.&nbsp;<\/p>\n\n\n\n<p>Finalmente destac\u00f3 que la ley Yolanda \u201ctiene como objetivo que los tres poderes del Estado puedan actuar en consecuencia y por eso ser\u00eda importante que se acepte el tratamiento de nuestro proyecto presentado meses atr\u00e1s que establece la emergencia en la cordillera a raiz de los incendios forestales\u201d.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/18\/rio-negro-tendra-ley-de-educacion-ambiental-para-funcionarios-publicos\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La Legislatura rionegrina aprob\u00f3 en primera vuelta el proyecto de adhesi\u00f3n a la Ley N\u00ba 27.592, m\u00e1s conocida como \u201cLey Yolanda\u201d.&nbsp; La iniciativa parlamentaria elaborada por los legisladores del Frente de Todos, Facundo Montecino Odarda y&nbsp; Jos\u00e9 Luis Berros -al que luego se sum\u00f3 la legisladora de Juntos Somos R\u00edo Negro Helena Herrero- establece la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4480"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4484"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}