{"id":4314,"date":"2021-06-15T14:25:27","date_gmt":"2021-06-15T14:25:27","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=4314"},"modified":"2021-06-15T14:26:05","modified_gmt":"2021-06-15T14:26:05","slug":"covid-en-patagones-a-la-fecha-son-483-los-positivos-activos-y-102-los-fallecidos","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/15\/covid-en-patagones-a-la-fecha-son-483-los-positivos-activos-y-102-los-fallecidos\/","title":{"rendered":"COVID en Patagones: A la fecha son 483 los positivos activos y 102 los fallecidos."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4314\" class=\"elementor elementor-4314\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21624880 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21624880\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5db1606a\" data-id=\"5db1606a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f342dbd elementor-widget elementor-widget-text-editor\" data-id=\"1f342dbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>La Secretar\u00eda de Salud de Patagones confirm\u00f3 que se registraron 30 nuevos casos positivos de COVID en Patagones.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, fueron descartados 27 sospechosos, mientras que 64 pacientes recibieron el alta.&nbsp;<\/p>\n\n\n\n<p>A la fecha, son 483 los positivos activos, 3852 los estudios con resultado negativo y 3008 los pacientes recuperados.&nbsp;<\/p>\n\n\n\n<p>En las \u00faltimas horas se registraron dos fallecimientos, por lo que, desde el inicio de la pandemia, suman 102 los decesos.&nbsp;<\/p>\n\n\n\n<p>Se recomienda continuar con las medidas preventivas; uso del cubrebocas, constante lavado de manos y el uso de alcohol.&nbsp;&nbsp;<\/p>\n\n\n\n<p>La actualizaci\u00f3n de datos con respecto al COVID estar\u00e1 disponible diariamente, a trav\u00e9s de los canales oficiales.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/06\/15\/covid-en-patagones-a-la-fecha-son-483-los-positivos-activos-y-102-los-fallecidos\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Salud de Patagones confirm\u00f3 que se registraron 30 nuevos casos positivos de COVID en Patagones.&nbsp; Adem\u00e1s, fueron descartados 27 sospechosos, mientras que 64 pacientes recibieron el alta.&nbsp; A la fecha, son 483 los positivos activos, 3852 los estudios con resultado negativo y 3008 los pacientes recuperados.&nbsp; En las \u00faltimas horas se registraron [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-4314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=4314"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/4314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/4315"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=4314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=4314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=4314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}