{"id":42667,"date":"2025-10-22T22:14:31","date_gmt":"2025-10-23T01:14:31","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=42667"},"modified":"2025-10-22T22:14:33","modified_gmt":"2025-10-23T01:14:33","slug":"un-joven-necesita-ayuda-para-una-operacion-urgente","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/10\/22\/un-joven-necesita-ayuda-para-una-operacion-urgente\/","title":{"rendered":"Un joven necesita ayuda para una operaci\u00f3n urgente"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><a><\/a>La Fundaci\u00f3n M\u00e1s Que Vencedores lanz\u00f3 una campa\u00f1a solidaria para colaborar con Leonel Ramos, un joven que sufri\u00f3 un accidente y necesita ser operado de urgencia.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u201cPor favor, mis amados, vamos a dar difusi\u00f3n a esto. Est\u00e1 muy delicado el muchacho y necesitamos ayudar, muchas gracias\u201d, expresaron desde la fundaci\u00f3n, apelando a la solidaridad de la comunidad.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Leonel requiere una intervenci\u00f3n m\u00e9dica costosa y su familia no cuenta con los recursos necesarios para cubrirla. Por eso, se est\u00e1n recaudando fondos para poder concretar la operaci\u00f3n cuanto antes.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Cada aporte es importante para acompa\u00f1ar a Leonel en este momento dif\u00edcil. Quienes deseen colaborar pueden hacerlo a trav\u00e9s del alias fundacionmqv o comunicarse al 2920270266.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Desde la fundaci\u00f3n remarcaron que toda ayuda suma y agradecieron la colaboraci\u00f3n de los vecinos que ya se est\u00e1n sumando a la campa\u00f1a.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>\n\n\n\n<p><\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/10\/22\/un-joven-necesita-ayuda-para-una-operacion-urgente\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n M\u00e1s Que Vencedores lanz\u00f3 una campa\u00f1a solidaria para colaborar con Leonel Ramos, un joven que sufri\u00f3 un accidente y necesita ser operado de urgencia. \u201cPor favor, mis amados, vamos a dar difusi\u00f3n a esto. Est\u00e1 muy delicado el muchacho y necesitamos ayudar, muchas gracias\u201d, expresaron desde la fundaci\u00f3n, apelando a la solidaridad de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":42668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-42667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=42667"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42667\/revisions"}],"predecessor-version":[{"id":42669,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42667\/revisions\/42669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/42668"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=42667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=42667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=42667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}