{"id":42647,"date":"2025-10-22T00:44:40","date_gmt":"2025-10-22T03:44:40","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=42647"},"modified":"2025-10-22T00:44:43","modified_gmt":"2025-10-22T03:44:43","slug":"encontraron-el-cuerpo-de-un-hombre-en-el-rio","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/10\/22\/encontraron-el-cuerpo-de-un-hombre-en-el-rio\/","title":{"rendered":"Encontraron el cuerpo de un hombre en el r\u00edo"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Este martes, personal de Prefectura Naval Argentina hall\u00f3 el cuerpo de un hombre en el r\u00edo Negro, a la altura del kil\u00f3metro 58, en cercan\u00edas de la balsa de Guardia Mitre, del lado de Conesa. Por el momento, las autoridades no lograron confirmar su identidad.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">El comisario Gustavo Rodr\u00edguez inform\u00f3 que el hallazgo se produjo en el marco de un rastrillaje ordenado por la Fiscal\u00eda, que investigaba dos denuncias paralelas: la desaparici\u00f3n de Carlos Tomassini de 20 a\u00f1os y una causa de abigeato en la que se busca a un sospechoso que habr\u00eda intentado escapar cruzando el r\u00edo.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Seg\u00fan detall\u00f3 el Ministerio P\u00fablico Fiscal, una de las denuncias corresponde a la familia de Carlos Alberto Tomasini, oriundo de Viedma, visto por \u00faltima vez el 8 de octubre. La segunda l\u00ednea de investigaci\u00f3n se vincula a un hombre pr\u00f3fugo por robo de ganado, cuyo paradero se desconoce desde hace varios d\u00edas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La autopsia se realizar\u00e1 este mi\u00e9rcoles, con el fin de establecer las causas del deceso y confirmar si el cuerpo corresponde a alguna de las dos personas buscadas.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/10\/22\/encontraron-el-cuerpo-de-un-hombre-en-el-rio\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Este martes, personal de Prefectura Naval Argentina hall\u00f3 el cuerpo de un hombre en el r\u00edo Negro, a la altura del kil\u00f3metro 58, en cercan\u00edas de la balsa de Guardia Mitre, del lado de Conesa. Por el momento, las autoridades no lograron confirmar su identidad. El comisario Gustavo Rodr\u00edguez inform\u00f3 que el hallazgo se produjo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":42649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-42647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=42647"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42647\/revisions"}],"predecessor-version":[{"id":42648,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/42647\/revisions\/42648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/42649"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=42647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=42647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=42647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}