{"id":40330,"date":"2025-05-16T11:25:30","date_gmt":"2025-05-16T14:25:30","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=40330"},"modified":"2025-05-16T11:42:44","modified_gmt":"2025-05-16T14:42:44","slug":"la-municipalidad-de-patagones-analiza-aumentar-las-tasas-municipales","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/05\/16\/la-municipalidad-de-patagones-analiza-aumentar-las-tasas-municipales\/","title":{"rendered":"La Municipalidad de Patagones analiz\u00e1 aumentar las tasas municipales"},"content":{"rendered":"\n<p>El secretario de gobierno H\u00e9ctor Otero indic\u00f3 que en los pr\u00f3ximos d\u00edas, la municipalidad de Patagones analiz\u00e1 aumentar la tasas municipales;<\/p>\n\n\n\n<p><strong>\u00abNosotros propusimos aumentar las tasas porque estamos cobrando la tasa de recolecci\u00f3n de residuos con valores del 2023 y se lo planteamos a la oposici\u00f3n que no nos acompa\u00f1o en esto\u00bb <\/strong><\/p>\n\n\n\n<p>Agreg\u00f3<strong> \u00abLa oposici\u00f3n debe entender que el pueblo pidio un cambio y no hay que poner palos en la rueda\u00bb.<\/strong><\/p>\n\n\n\n<p>Con respecto a la Fiscal Impositiva Otero coment\u00f3<strong> \u00abEsperemos que el Concejo Deliberante reflexione sobre la fiscal impositiva y que otorgue al menos una ecuaci\u00f3n con respecto al valor porque el vecino tiene que tener recolecci\u00f3n de residuos\u00bb<\/strong><\/p>\n\n\n\n<p><strong>\u00abEstamos esperando que se dirima la cuestion organizativa en el concejo deliberante en cuanto a las autoridades e ingresar\u00e1 el proyecto nuevo de fiscal Impositiva porque creemos que los valores estan muy desajustados en todas las tasas, pero en particular, en la recolecci\u00f3n de residuos y en eso tiene mucha responsabilidad la oposici\u00f3n<\/strong>\u00bb finaliz\u00f3 el secretario de Gobierno de Patagones.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"251\" height=\"201\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2025\/05\/otero-1.png\" alt=\"\" class=\"wp-image-40334\"\/><\/figure>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/05\/16\/la-municipalidad-de-patagones-analiza-aumentar-las-tasas-municipales\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El secretario de gobierno H\u00e9ctor Otero indic\u00f3 que en los pr\u00f3ximos d\u00edas, la municipalidad de Patagones analiz\u00e1 aumentar la tasas municipales; \u00abNosotros propusimos aumentar las tasas porque estamos cobrando la tasa de recolecci\u00f3n de residuos con valores del 2023 y se lo planteamos a la oposici\u00f3n que no nos acompa\u00f1o en esto\u00bb Agreg\u00f3 \u00abLa oposici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-40330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=40330"}],"version-history":[{"count":2,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40330\/revisions"}],"predecessor-version":[{"id":40337,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40330\/revisions\/40337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/40333"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=40330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=40330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=40330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}