{"id":40326,"date":"2025-05-15T13:42:57","date_gmt":"2025-05-15T16:42:57","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=40326"},"modified":"2025-05-15T13:42:58","modified_gmt":"2025-05-15T16:42:58","slug":"convocatoria-a-elecciones-de-juntas-vecinales-en-los-barrios-piedrabuena-y-curru-leuvu","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/05\/15\/convocatoria-a-elecciones-de-juntas-vecinales-en-los-barrios-piedrabuena-y-curru-leuvu\/","title":{"rendered":"Convocatoria a elecciones de juntas vecinales en los barrios Piedrabuena y Curr\u00fa Leuv\u00fa"},"content":{"rendered":"\n<p>La Municipalidad de Viedma informa a los vecinos de los barrios Piedrabuena y Curr\u00fa Leuv\u00fa sobre la convocatoria a elecciones para renovar las autoridades de sus respectivas juntas vecinales.<\/p>\n\n\n\n<p>Los comicios se llevar\u00e1n a cabo el pr\u00f3ximo s\u00e1bado 28 de junio.<\/p>\n\n\n\n<p>A partir de la publicaci\u00f3n de esta convocatoria, se inician los plazos para diversos tr\u00e1mites electorales, incluyendo la incorporaci\u00f3n a los padrones definitivos y la presentaci\u00f3n de listas de candidatos.<\/p>\n\n\n\n<p>Seg\u00fan inform\u00f3 la Junta Electoral Municipal, el plazo para solicitar la inclusi\u00f3n, modificaci\u00f3n o exclusi\u00f3n de vecinos en los padrones provisorios vence el mi\u00e9rcoles 28 de mayo.<\/p>\n\n\n\n<p>Los padrones definitivos de ambos barrios ser\u00e1n publicados el jueves 29 de mayo.<\/p>\n\n\n\n<p>La fecha l\u00edmite para la presentaci\u00f3n de listas de candidatos es el mi\u00e9rcoles 28 de mayo, en la sede de la Junta Electoral Municipal, ubicada en Brown 161, en el horario de 9 a 13 y de 18 a 20.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2025\/05\/15\/convocatoria-a-elecciones-de-juntas-vecinales-en-los-barrios-piedrabuena-y-curru-leuvu\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Viedma informa a los vecinos de los barrios Piedrabuena y Curr\u00fa Leuv\u00fa sobre la convocatoria a elecciones para renovar las autoridades de sus respectivas juntas vecinales. Los comicios se llevar\u00e1n a cabo el pr\u00f3ximo s\u00e1bado 28 de junio. A partir de la publicaci\u00f3n de esta convocatoria, se inician los plazos para diversos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[38],"tags":[],"class_list":["post-40326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=40326"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40326\/revisions"}],"predecessor-version":[{"id":40328,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/40326\/revisions\/40328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/40327"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=40326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=40326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=40326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}