{"id":38243,"date":"2024-06-21T23:11:38","date_gmt":"2024-06-22T02:11:38","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=38243"},"modified":"2024-06-21T23:11:39","modified_gmt":"2024-06-22T02:11:39","slug":"patagones-se-rompio-union-por-la-patria-y-carlos-videla-tiene-su-propio-bloque","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/21\/patagones-se-rompio-union-por-la-patria-y-carlos-videla-tiene-su-propio-bloque\/","title":{"rendered":"PATAGONES: Se rompi\u00f3 Uni\u00f3n por la Patria y Carlos Videla tiene su propio Bloque"},"content":{"rendered":"\n<p>El concejal Carlos Videla habia anticipado que la relaci\u00f3n con los dem\u00e1s concejales de Uni\u00f3n por la Patria no era buena. <\/p>\n\n\n\n<p>Lo mismo pasaba con el Intendente Ricardo Marino, quien habia expresado en el acto por el D\u00eda del trabajador un mensaje que muchos identificaron que era para Carlos Videla y se daba el punto de inflexi\u00f3n entre el intendente y el concejal. <\/p>\n\n\n\n<p>Las diferencias eran notorias y eso se pudo observar cuando el Concejal Videla gestion\u00f3 por su propia voluntad la entrega de le\u00f1a para los vecinos de Patagones.<\/p>\n\n\n\n<p>Es que la Municipalidad de Patagones, no habia entregado la le\u00f1a a los vecinos que mas necesitaban y Carlos Videla consigui\u00f3 un cami\u00f3n con le\u00f1a y empez\u00f3 a entregarla por distintos sectores. <\/p>\n\n\n\n<p>Esto molesto al ejecutivo de Patagones y a varios concejales de Uni\u00f3n por la Patria, por lo que la diferencia se ampliaba cada vez m\u00e1s. <\/p>\n\n\n\n<p>En el Concejo Deliberante de Patagones existia distancia entre la presidenta del Concejo y Carlos Videla. <\/p>\n\n\n\n<p>Seg\u00fan los comentarios del concejal <strong>\u00abLa presidenta Cinirella nunca me escuch\u00f3 y me esquivaba\u00bb<\/strong><\/p>\n\n\n\n<p>Es por eso que Videla present\u00f3 su propio bloque bajo el nombre <strong>\u00abPatria de los Comunes\u00bb <\/strong>y ahora el clima se pone tenso con otro bloque que puede cambiar las decisiones que se toman en el poder legislativo local en Patagones. <\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/21\/patagones-se-rompio-union-por-la-patria-y-carlos-videla-tiene-su-propio-bloque\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El concejal Carlos Videla habia anticipado que la relaci\u00f3n con los dem\u00e1s concejales de Uni\u00f3n por la Patria no era buena. Lo mismo pasaba con el Intendente Ricardo Marino, quien habia expresado en el acto por el D\u00eda del trabajador un mensaje que muchos identificaron que era para Carlos Videla y se daba el punto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-38243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actores-politicos"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=38243"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38243\/revisions"}],"predecessor-version":[{"id":38245,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38243\/revisions\/38245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/38244"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=38243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=38243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=38243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}