{"id":38211,"date":"2024-06-18T18:06:25","date_gmt":"2024-06-18T21:06:25","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=38211"},"modified":"2024-06-18T18:06:27","modified_gmt":"2024-06-18T21:06:27","slug":"continuan-las-castraciones-en-viedma","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/18\/continuan-las-castraciones-en-viedma\/","title":{"rendered":"Contin\u00faan las Castraciones en Viedma"},"content":{"rendered":"\n<p>Esta semana contin\u00faa la campa\u00f1a de castraci\u00f3n para gatos y perros en la Junta Vecinal del Barrio Los Fresnos (Rio Villegas 1774).<\/p>\n\n\n\n<p>Las castraciones son sin turno y por orden de llegada de 8:30 a 12:30 horas (las castraciones son hasta las 11:30). <\/p>\n\n\n\n<p>Se aplican vacunas antirr\u00e1bicas, pero por el momento no se entregan antiparasitarios.<\/p>\n\n\n\n<p>Las castraciones contin\u00faan la semana del 24 de junio hasta el 5 de julio en la Junta Vecinal del Barrio Parque Independencia (Giachino 303 esquina Las Madreselvas). <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>IMPORTANTE<\/strong><\/p>\n\n\n\n<p>\u25cf Llevar a los animales con 12 horas de ayuno y traer manta o frazada para envolverlos.<\/p>\n\n\n\n<p>\u25cf Perros con correa y bozal.<\/p>\n\n\n\n<p>\u25cf Gatos en casas de transporte, mochila o bolso con cierre.<\/p>\n\n\n\n<p><\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/18\/continuan-las-castraciones-en-viedma\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Esta semana contin\u00faa la campa\u00f1a de castraci\u00f3n para gatos y perros en la Junta Vecinal del Barrio Los Fresnos (Rio Villegas 1774). Las castraciones son sin turno y por orden de llegada de 8:30 a 12:30 horas (las castraciones son hasta las 11:30). Se aplican vacunas antirr\u00e1bicas, pero por el momento no se entregan antiparasitarios. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-38211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=38211"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38211\/revisions"}],"predecessor-version":[{"id":38214,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38211\/revisions\/38214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/38213"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=38211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=38211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=38211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}