{"id":38169,"date":"2024-06-09T21:39:23","date_gmt":"2024-06-10T00:39:23","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=38169"},"modified":"2024-06-09T21:39:25","modified_gmt":"2024-06-10T00:39:25","slug":"la-municipalidad-de-patagones-solo-entrego-el-boleto-estudiantil-para-universitario-y-terciario-que-pasa-con-los-alumnos-de-primaria-y-secundaria","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/09\/la-municipalidad-de-patagones-solo-entrego-el-boleto-estudiantil-para-universitario-y-terciario-que-pasa-con-los-alumnos-de-primaria-y-secundaria\/","title":{"rendered":"La Municipalidad de Patagones solo entrego el boleto estudiantil para Universitario y Terciario \u00bfQu\u00e9 pasa con los alumnos de Primaria y Secundaria?"},"content":{"rendered":"\n<p>El ciclo lectivo 2024 comenz\u00f3 el 1 de marzo en varias provincias de Argentina. Tal es el caso de varios establecimientos educativos en Viedma y Patagones.<\/p>\n\n\n\n<p>Todos los a\u00f1os se entrega el boleto estudiantil para aquellos alumnos que se anotan en un listado y pueden asistir todos los dias a sus establecimientos educativos. <\/p>\n\n\n\n<p>Este a\u00f1o, Patagones vive una de las peores situaciones con respecto al boleto estudiantil, porque el gobierno municipal de Ricardo Marino y su gesti\u00f3n, no le puede encontrar la vuelta. Ya sea por ignoracia, falta de capacidad o no escuchar a los que tienen conocimiento y experiencia.<\/p>\n\n\n\n<p>Recien en junio, faltando algunas semanas para que empiece el receso invernal, la Municipalidad de Patagones di\u00f3 a conocer el listado de los estudiantes universitarios y terciarios que salieron beneficiados para recibir el boleto estudiantil. <\/p>\n\n\n\n<p>Existe disgusto de varios estudiantes que quedaron afuera del listado y no cuentan con la ayuda de la municipalidad. Se suma a esta situaci\u00f3n, la espera de los que si salieron beneficiados, pero todav\u00eda no recibieron nada. <\/p>\n\n\n\n<p>Solo quedan dos semanas para que varios estudiantes universitarios y terciarios terminen su cursada en el primer cuatrimestre y no deben cursar mas hasta el mes de agosto. <\/p>\n\n\n\n<p>Los boletos que le entregaron no es para todos los dias (lunes a viernes) y no les alcanza para ir a estudiar. Esto, desiluciona a todos los estudiantes.<\/p>\n\n\n\n<p>Sin embargo, muchos quedaron afuera y no recibieron ninguna respuesta de cuando van a tener el mismo beneficio.<\/p>\n\n\n\n<p><strong>\u00bfHabr\u00e1 manifestaci\u00f3n  o reclamo de la sociedad ante este problema como lo vienen haciendo con Naci\u00f3n? \u00bfQu\u00e9 sucede con los gremios, docentes y familia que no salen a reclamar al Municipio de Patagones?<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>SIN NOTICIAS POR EL BOLETO ESTUDIANTIL PARA PRIMARIA Y SECUNDARIA<\/strong><\/p>\n\n\n\n<p>Otro problema que se le suma a la Gesti\u00f3n del Intendente Marino y su Gobierno es la situaci\u00f3n del Boleto Estudiantil para los alumnos de primaria y secundaria. Es que todav\u00eda no hay informacion de cuando se entragara el boleto a los beneficiarios. <\/p>\n\n\n\n<p>Adem\u00e1s, las clases finalizan en algunas semanas cuando comience el receso invernal. <\/p>\n\n\n\n<p>Muchos vecinos no pueden llevar todos los d\u00edas a sus hijos a las escuelas por este problema y este a\u00f1o no tienen el acompa\u00f1amiento del Estado Municipal. <\/p>\n\n\n\n<p>Adem\u00e1s, se suma la falta del colectivo urbano en Patagones que no funcion\u00f3 durante todo el a\u00f1o y tanto la empresa, como el municipio, no se hacen cargo de dar una respuesta. <\/p>\n\n\n\n<p>Esta situaci\u00f3n agrava cada vez mas el clima social, educativo y pol\u00edtico en Patagones. <\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/09\/la-municipalidad-de-patagones-solo-entrego-el-boleto-estudiantil-para-universitario-y-terciario-que-pasa-con-los-alumnos-de-primaria-y-secundaria\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>El ciclo lectivo 2024 comenz\u00f3 el 1 de marzo en varias provincias de Argentina. Tal es el caso de varios establecimientos educativos en Viedma y Patagones. Todos los a\u00f1os se entrega el boleto estudiantil para aquellos alumnos que se anotan en un listado y pueden asistir todos los dias a sus establecimientos educativos. Este a\u00f1o, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-38169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=38169"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38169\/revisions"}],"predecessor-version":[{"id":38171,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38169\/revisions\/38171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/38170"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=38169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=38169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=38169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}