{"id":38135,"date":"2024-06-03T18:06:53","date_gmt":"2024-06-03T21:06:53","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=38135"},"modified":"2024-06-03T18:06:54","modified_gmt":"2024-06-03T21:06:54","slug":"operativos-de-transito-secuestraron-varios-vehiculos-este-fin-de-semana","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/03\/operativos-de-transito-secuestraron-varios-vehiculos-este-fin-de-semana\/","title":{"rendered":"Operativos de tr\u00e1nsito:  Secuestraron varios veh\u00edculos este fin de semana"},"content":{"rendered":"\n<p>La Municipalidad de Viedma inform\u00f3 que durante los operativos de tr\u00e1nsito realizados este fin de semana se secuestraron un total de diez veh\u00edculos.<\/p>\n\n\n\n<p>Del total de rodados retenidos, cinco fueron debido a la falta de documentaci\u00f3n y los otros cinco por alcoholemia positiva.<br>El titular de la Agencia Local de Seguridad Vial, Jorge Vilca, manifest\u00f3 que \u201cestos resultados se obtienen mediante el trabajo mancomunado con personal de la Polic\u00eda de R\u00edo Negro\u00bb.<\/p>\n\n\n\n<p>El \u00e1rea continuar\u00e1 trabajando en conjunto con las fuerzas de seguridad para garantizar el cumplimiento de las normativas de tr\u00e1nsito<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/06\/03\/operativos-de-transito-secuestraron-varios-vehiculos-este-fin-de-semana\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Viedma inform\u00f3 que durante los operativos de tr\u00e1nsito realizados este fin de semana se secuestraron un total de diez veh\u00edculos. Del total de rodados retenidos, cinco fueron debido a la falta de documentaci\u00f3n y los otros cinco por alcoholemia positiva.El titular de la Agencia Local de Seguridad Vial, Jorge Vilca, manifest\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-38135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=38135"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38135\/revisions"}],"predecessor-version":[{"id":38137,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38135\/revisions\/38137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/38136"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=38135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=38135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=38135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}