{"id":38006,"date":"2024-04-25T19:36:09","date_gmt":"2024-04-25T22:36:09","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=38006"},"modified":"2024-04-25T19:37:08","modified_gmt":"2024-04-25T22:37:08","slug":"manana-sera-la-sesion-conjunta-de-los-concejales-deliberantes-de-viedma-y-patagones","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/04\/25\/manana-sera-la-sesion-conjunta-de-los-concejales-deliberantes-de-viedma-y-patagones\/","title":{"rendered":"Ma\u00f1ana ser\u00e1 la Sesi\u00f3n Conjunta en el Concejo Deliberante de Viedma"},"content":{"rendered":"\n<p><br>Este Viernes 26 de abril se llevar\u00e1 a cabo la XIX Sesi\u00f3n Conjunta de los Concejos Deliberantes de Viedma y Patagones, en el marco del bicentesimo cuadrag\u00e9simo quinto aniversario de la fundaci\u00f3n de ambas ciudades.<\/p>\n\n\n\n<p>A las 10 de la ma\u00f1ana, en la sede del parlamento viedmense -Buenos Aires 320- est\u00e1 previsto el acto de Apertura que sera presidido por Mariel Cinirella y Pedro Bichara y contar\u00e1 con la presencia de los intendentes Ricardo Marino y Marcos Castro.<\/p>\n\n\n\n<p>Junto a las cuestiones protocolares, las y los concejales tratar\u00e1n temas relativos a la realidad comarcal.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/04\/25\/manana-sera-la-sesion-conjunta-de-los-concejales-deliberantes-de-viedma-y-patagones\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Este Viernes 26 de abril se llevar\u00e1 a cabo la XIX Sesi\u00f3n Conjunta de los Concejos Deliberantes de Viedma y Patagones, en el marco del bicentesimo cuadrag\u00e9simo quinto aniversario de la fundaci\u00f3n de ambas ciudades. A las 10 de la ma\u00f1ana, en la sede del parlamento viedmense -Buenos Aires 320- est\u00e1 previsto el acto de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-38006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=38006"}],"version-history":[{"count":2,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38006\/revisions"}],"predecessor-version":[{"id":38009,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/38006\/revisions\/38009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/38007"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=38006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=38006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=38006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}