{"id":37786,"date":"2024-03-26T15:56:50","date_gmt":"2024-03-26T18:56:50","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=37786"},"modified":"2024-03-26T15:56:51","modified_gmt":"2024-03-26T18:56:51","slug":"semana-santa-en-la-comarca-castro-y-marino-presentan-propuestas-en-conjunto","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/26\/semana-santa-en-la-comarca-castro-y-marino-presentan-propuestas-en-conjunto\/","title":{"rendered":"Semana Santa en La Comarca: Castro y Marino presentan propuestas en conjunto"},"content":{"rendered":"\n<p>Ma\u00f1ana, mi\u00e9rcoles 27 de marzo, a las 9.30 horas, el Intendente Ricardo Marino, junto a su par de Viedma, Marcos Castro, ofrecer\u00e1n una conferencia de prensa con el objetivo de presentar las actividades previstas para el fin de semana largo, en el marco de la celebraci\u00f3n de Semana Santa.<\/p>\n\n\n\n<p>La actividad tendr\u00e1 lugar en la Oficina de Informes Tur\u00edsticos recientemente inaugurada en la capital provincial.<\/p>\n\n\n\n<p>El encuentro y la difusi\u00f3n conjunta de las actividades refuerza lo conversado entre los mandatarios oportunamente, al iniciar sus mandatos, cuando acordaron trabajar para fortalecer los lazos comarcarles, teniendo en cuenta la riqueza hist\u00f3rica y las bondades naturales que hermanan a las dos ciudades.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/26\/semana-santa-en-la-comarca-castro-y-marino-presentan-propuestas-en-conjunto\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana, mi\u00e9rcoles 27 de marzo, a las 9.30 horas, el Intendente Ricardo Marino, junto a su par de Viedma, Marcos Castro, ofrecer\u00e1n una conferencia de prensa con el objetivo de presentar las actividades previstas para el fin de semana largo, en el marco de la celebraci\u00f3n de Semana Santa. La actividad tendr\u00e1 lugar en la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-37786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=37786"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37786\/revisions"}],"predecessor-version":[{"id":37788,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37786\/revisions\/37788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/37787"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=37786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=37786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=37786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}