{"id":37758,"date":"2024-03-23T17:32:36","date_gmt":"2024-03-23T20:32:36","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=37758"},"modified":"2024-03-23T17:32:37","modified_gmt":"2024-03-23T20:32:37","slug":"continuan-las-inscripciones-para-los-talleres-culturales-en-viedma","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/23\/continuan-las-inscripciones-para-los-talleres-culturales-en-viedma\/","title":{"rendered":"Contin\u00faan las inscripciones para los Talleres Culturales en Viedma"},"content":{"rendered":"\n<p>Son varios los talleres que dicta la Municipalidad de Viedma y las inscripciones contin\u00faan abiertas. <\/p>\n\n\n\n<p>Las inscripciones son presenciales con fotocopia de DNI (del adulto y del menor en caso de inscripci\u00f3n de menores)<\/p>\n\n\n\n<p>\u25cf <strong>Centro Cultural<\/strong><\/p>\n\n\n\n<p>T\u1d00\u029f\u029f\u1d07\u0280 \u029f\u026a\u1d1b\u1d07\u0280\u1d00\u0280\u026a\u1d0f (\u1d00 \u1d18\u1d00\u0280\u1d1b\u026a\u0280 \u1d05\u1d07 15 \u1d00\u0274\u0303\u1d0fs)<\/p>\n\n\n\n<p>T\u1d00\u029f\u029f\u1d07\u0280 \u1d05\u1d07 \u1d00\u1d07\u0280\u1d0f\u0301\u0493\u1d0f\u0274\u1d0fs \u026a\u0274\u0493\u1d00\u0274\u1d1b\u026a\u029f, \u1d0a\u1d0f\u1d20\u1d07\u0274\u1d07s \u028f \u1d00\u1d05\u1d1c\u029f\u1d1b\u1d0fs<\/p>\n\n\n\n<p>T\u1d00\u029f\u029f\u1d07\u0280 \u1d05\u1d07 \u0280\u1d07\u1d00\u029f\u026a\u1d22\u1d00\u1d04\u026a\u1d0f\u0274 \u1d05\u1d07 \u1d1b\u026a\u1d1b\u1d07\u0280\u1d07s \u1d0a\u1d0f\u1d20\u1d07\u0274\u1d07s \u028f \u1d00\u1d05\u1d1c\u029f\u1d1b\u1d0fs<\/p>\n\n\n\n<p>C\u1d0f\u0280\u1d0f \u1d0a\u1d1c\u1d20\u1d07\u0274\u026a\u029f \u1d0d\u026ax\u1d1b\u1d0f<\/p>\n\n\n\n<p>E\u0274s\u1d00\u1d0d\u0299\u029f\u1d07 \u1d05\u1d07 \u1d0d\u1d1cs\u026a\u1d04\u1d00 \u1d18\u1d0f\u1d18\u1d1c\u029f\u1d00\u0280 \u029f\u1d00\u1d1b\u026a\u0274\u1d0f\u1d00\u1d0d\u1d07\u0280\u026a\u1d04\u1d00\u0274\u1d0f ( \u1d00\u1d05\u1d1c\u029f\u1d1b\u1d0fs)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u25cf <strong>Centro Cultural 2<\/strong><\/p>\n\n\n\n<p>G\u1d1c\u026a\u1d1b\u1d00\u0280\u0280\u1d00 \u1d00\u1d05\u1d1c\u029f\u1d1b\u1d0fs<\/p>\n\n\n\n<p>T\u1d07\u1d00\u1d1b\u0280\u1d0f \u1d00\u1d05\u1d0f\u029f\u1d07s\u1d04\u1d07\u0274\u1d1b\u1d07s<\/p>\n\n\n\n<p>G\u1d1c\u026a\u1d1b\u1d00\u0280\u0280\u1d00 \u1d07\u0274 \u1d04\u1d0f\u0274\u1d0a\u1d1c\u0274\u1d1b\u1d0f (12 \u1d00 18 \u1d00\u0274\u0303\u1d0fs)<\/p>\n\n\n\n<p>S\u1d07\u1d0d\u026a\u029f\u029f\u1d07\u0280\u1d0f \u1d05\u1d07 \u1d0d\u1d0f\u1d20\u026a\u1d0d\u026a\u1d07\u0274\u1d1b\u1d0fs \u1d04\u0280\u1d07\u1d00\u1d1b\u026a\u1d20\u1d0fs ( 7 \u1d00 12 \u1d00\u0274\u0303\u1d0fs)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u25cf<strong>Talleres con cupo abierto<\/strong><\/p>\n\n\n\n<p>\u1d1b\u1d00\u0274\u0262\u1d0f<\/p>\n\n\n\n<p>C\u1d0f\u0280\u1d0f \u1d05\u1d07 \u0274\u026a\u0274\u0303\u1d0fs<\/p>\n\n\n\n<p>C\u1d00\u0274\u1d1b\u1d0f\u0280\u1d00s \u0262\u0280\u1d1c\u1d18\u1d0f \u1d20\u1d0f\u1d04\u1d00\u029f \u0493\u1d07\u1d0d\u1d07\u0274\u026a\u0274\u1d0f<\/p>\n\n\n\n<p>Danza para la transformaci\u00f3n social (se dicta en el CaMu)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Adem\u00e1s siguen abiertas las audiciones para formar parte del Coro Municipal, los lunes y jueves a las 20hs.<\/p>\n\n\n\n<p>Ra\u00edz Folkl\u00f3rica, grupo municipal de Danzas. Lunes y mi\u00e9rcoles 18hs. Contin\u00faan las inscripciones para la Formaci\u00f3n B\u00e1sica en Danzas Folkl\u00f3ricas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225350262-1024x682.jpg\" alt=\"\" class=\"wp-image-37760\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225350262-1024x682.jpg 1024w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225350262-300x200.jpg 300w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225350262-768x512.jpg 768w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225350262.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225354370-1024x682.jpg\" alt=\"\" class=\"wp-image-37761\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225354370-1024x682.jpg 1024w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225354370-300x200.jpg 300w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225354370-768x512.jpg 768w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1711225354370.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/23\/continuan-las-inscripciones-para-los-talleres-culturales-en-viedma\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Son varios los talleres que dicta la Municipalidad de Viedma y las inscripciones contin\u00faan abiertas. Las inscripciones son presenciales con fotocopia de DNI (del adulto y del menor en caso de inscripci\u00f3n de menores) \u25cf Centro Cultural T\u1d00\u029f\u029f\u1d07\u0280 \u029f\u026a\u1d1b\u1d07\u0280\u1d00\u0280\u026a\u1d0f (\u1d00 \u1d18\u1d00\u0280\u1d1b\u026a\u0280 \u1d05\u1d07 15 \u1d00\u0274\u0303\u1d0fs) T\u1d00\u029f\u029f\u1d07\u0280 \u1d05\u1d07 \u1d00\u1d07\u0280\u1d0f\u0301\u0493\u1d0f\u0274\u1d0fs \u026a\u0274\u0493\u1d00\u0274\u1d1b\u026a\u029f, \u1d0a\u1d0f\u1d20\u1d07\u0274\u1d07s \u028f \u1d00\u1d05\u1d1c\u029f\u1d1b\u1d0fs T\u1d00\u029f\u029f\u1d07\u0280 \u1d05\u1d07 \u0280\u1d07\u1d00\u029f\u026a\u1d22\u1d00\u1d04\u026a\u1d0f\u0274 \u1d05\u1d07 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-37758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-publicas"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=37758"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37758\/revisions"}],"predecessor-version":[{"id":37762,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37758\/revisions\/37762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/37759"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=37758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=37758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=37758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}