{"id":37719,"date":"2024-03-19T14:40:53","date_gmt":"2024-03-19T17:40:53","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=37719"},"modified":"2024-03-19T14:40:54","modified_gmt":"2024-03-19T17:40:54","slug":"mariel-cinirella-comenzo-con-el-programa-el-concejo-en-la-calle-escuchando-a-las-instituciones","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/19\/mariel-cinirella-comenzo-con-el-programa-el-concejo-en-la-calle-escuchando-a-las-instituciones\/","title":{"rendered":"Mariel Cinirella comenz\u00f3 con el programa \u00abEl concejo en la calle escuchando a las instituciones\u00bb"},"content":{"rendered":"\n<p>La presidenta del Honorable Concejo Deliberante de Patagones, Mariel Cinirella, inici\u00f3 su programa \u00abel Concejo en la calle escuchando a las instituciones \u00ab.<\/p>\n\n\n\n<p>La iniciativa se realiz\u00f3 con vecinos y vecinas de entidades de Stroeder, Bah\u00eda San Blas, J.B.Casas y Los Pocitos.<\/p>\n\n\n\n<p>Cinirella destac\u00f3 que \u00abnuestra mirada del Partido de Patagones es integral, con un o\u00eddo en la palabra de cada uno de sus habitantes\u00bb.<\/p>\n\n\n\n<p>La agenda de reuniones, abierta y disponible, se materializa durante los 365 d\u00edas del a\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869894689-1024x683.jpg\" alt=\"\" class=\"wp-image-37721\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869894689-1024x683.jpg 1024w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869894689-300x200.jpg 300w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869894689-768x512.jpg 768w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869894689.jpg 1079w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869897273-1024x683.jpg\" alt=\"\" class=\"wp-image-37722\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869897273-1024x683.jpg 1024w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869897273-300x200.jpg 300w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869897273-768x512.jpg 768w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2024\/03\/FB_IMG_1710869897273.jpg 1079w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/19\/mariel-cinirella-comenzo-con-el-programa-el-concejo-en-la-calle-escuchando-a-las-instituciones\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La presidenta del Honorable Concejo Deliberante de Patagones, Mariel Cinirella, inici\u00f3 su programa \u00abel Concejo en la calle escuchando a las instituciones \u00ab. La iniciativa se realiz\u00f3 con vecinos y vecinas de entidades de Stroeder, Bah\u00eda San Blas, J.B.Casas y Los Pocitos. Cinirella destac\u00f3 que \u00abnuestra mirada del Partido de Patagones es integral, con un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-37719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-esta-seccion"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=37719"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37719\/revisions"}],"predecessor-version":[{"id":37723,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37719\/revisions\/37723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/37720"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=37719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=37719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=37719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}