{"id":37672,"date":"2024-03-10T10:33:25","date_gmt":"2024-03-10T13:33:25","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=37672"},"modified":"2024-03-10T10:33:26","modified_gmt":"2024-03-10T13:33:26","slug":"lorena-villaverde-todos-debemos-hacer-el-sacrificio-y-celebro-la-decision-del-presidente","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/10\/lorena-villaverde-todos-debemos-hacer-el-sacrificio-y-celebro-la-decision-del-presidente\/","title":{"rendered":"Lorena Villaverde \u00abTodos debemos hacer el sacrificio y celebro la decisi\u00f3n del presidente\u00bb"},"content":{"rendered":"\n<p>La diputada Lorena Villaverde apoyo la medida del presidente de la Naci\u00f3n Javier Milei y dar marcha a tras a todos los aumentos para los funcionarios. <\/p>\n\n\n\n<p>Esta medida fue implementada por el gobierno de Cristina Fernandez de Kirchner durante su mandato en el a\u00f1o 2011 y hasta la actualidad los funcionarios se aumentaban el sueldo.<\/p>\n\n\n\n<p>La diputada Villaverde aclar\u00f3 \u00abLa situaci\u00f3n que esta atravesando el pa\u00eds amerita que el compromiso y el patriotismo nos permita caminar, no de espalda, al sacrificio que est\u00e1n llevando nuestros ciudadanos para hacer frente a la crisis\u00bb.<\/p>\n\n\n\n<p>Agreg\u00f3 \u00abTodos debemos hacer el sacrificio y celebro la decisi\u00f3n de nuestro presidente\u00bb.<\/p>\n\n\n\n<p>La funcionaria indic\u00f3 \u00abyo vengo del sector privado y hace un a\u00f1o que ingrese en la arena pol\u00edtica. Todos los a\u00f1os me ajuste y toda la vida\u00bb.<\/p>\n\n\n\n<p>Con respecto al recorte del salario de los funcionarios indic\u00f3 \u00abHoy entiendo que es un gesto que se debe hacer pero esto viene desde el 2011 atado al crecimiento y se mejoraba el salario a los empleados de la casta\u00bb.<\/p>\n\n\n\n<p>Por \u00faltimo finaliz\u00f3 \u00abA todos nos debe llegar ese ajuste y estoy de acuerdo en retrotraer el aumento de los funcionarios y hay que revisar el aumento de todos\u00bb.<\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2024\/03\/10\/lorena-villaverde-todos-debemos-hacer-el-sacrificio-y-celebro-la-decision-del-presidente\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>La diputada Lorena Villaverde apoyo la medida del presidente de la Naci\u00f3n Javier Milei y dar marcha a tras a todos los aumentos para los funcionarios. Esta medida fue implementada por el gobierno de Cristina Fernandez de Kirchner durante su mandato en el a\u00f1o 2011 y hasta la actualidad los funcionarios se aumentaban el sueldo. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-37672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actores-politicos"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=37672"}],"version-history":[{"count":1,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37672\/revisions"}],"predecessor-version":[{"id":37674,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/37672\/revisions\/37674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/37673"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=37672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=37672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=37672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}