{"id":1732,"date":"2021-04-10T03:16:46","date_gmt":"2021-04-10T03:16:46","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=1732"},"modified":"2021-04-10T03:34:04","modified_gmt":"2021-04-10T03:34:04","slug":"siempre-entendi-la-politica-como-una-herramienta-para-cambiar-la-realidad","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/04\/10\/siempre-entendi-la-politica-como-una-herramienta-para-cambiar-la-realidad\/","title":{"rendered":"Siempre entend\u00ed la pol\u00edtica como una herramienta para cambiar la realidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1732\" class=\"elementor elementor-1732\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36220ab7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36220ab7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff3f83b\" data-id=\"3ff3f83b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7d604f elementor-widget elementor-widget-text-editor\" data-id=\"5e7d604f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>Desde la Secretaria de Desarrollo Social de la Ciudad de Viedma se viene trabajando con distintos programas para la poblaci\u00f3n.<\/p>\n\n\n\n<p>Mario S\u00e1nchez, Secretario de Desarrollo Social, mencion\u00f3 que el trabajo llevado a cabo durante el a\u00f1o pasado permiti\u00f3 conocer la condici\u00f3n de la Ciudad y abordar distintas acciones por la segunda ola del Covid-19.<\/p>\n\n\n\n<p>\u201cNosotros estamos con el programa alimentario (PROA) con el fin de reducir las intervenciones directas en las casas de los vecinos que sabemos que en el marco de la pandemia son complicadas, estamos prepar\u00e1ndonos para esas circunstancias. Pens\u00e1bamos que iba a ser un a\u00f1o donde nos \u00edbamos a ocupar m\u00e1s de lo promocional y no tanto de lo asistencial pero visto c\u00f3mo evoluciona la segunda ola tendremos que poner la atenci\u00f3n en esta \u00e1rea\u201d Indic\u00f3 el secretario.<\/p>\n\n\n\n<p>Hay que recordar que el programa alimentario, es una pol\u00edtica p\u00fablica implementada por el Gobierno de Viedma en la Capital hist\u00f3rica de la Patagonia durante el a\u00f1o 2020 y apunta a brindar una asistencia a las familias que mas lo necesitan, a trav\u00e9s del uso de una tarjeta para la compra de distintos alimentos.<\/p>\n\n\n\n<p>Durante el 2021, contin\u00faan con esta Pol\u00edtica de Estado Municipal y se est\u00e1n preparando en el caso que se deba brindar asistencia a las personas aisladas producto del Covid-19, lo cual son una prioridad para la actual Gesti\u00f3n del Intendente Pedro Pesatti.<\/p>\n\n\n\n<p>Desde la Secretaria de Desarrollo Social, se viene trabajando con distintas capacitaciones para generar empleo y promoci\u00f3n social.<\/p>\n\n\n\n<p>El Gobierno de Viedma continua trabajando con los programas \u201cpunto digital\u201d y \u201cLaboratorio de Proyectos Digitales\u201d fomentando varios proyectos que est\u00e1n vinculados con la rob\u00f3tica, medio ambiente, cuidadores domiciliarios, entre otros.<\/p>\n\n\n\n<p>En los pr\u00f3ximos d\u00edas se llevara a cabo el proyecto de urbanizaci\u00f3n y la obra de cord\u00f3n cuneta y desag\u00fces pluviales en el barrio Progreso. Esta acci\u00f3n pol\u00edtica, fue producto de un trabajo coordinado con la secretaria de integraci\u00f3n socio-urbano de la Naci\u00f3n.<\/p>\n\n\n\n<p>\u201cEstamos en contacto permanente con el Intendente, en donde nos plantea la necesidad de actuar en el contexto que estamos atravesando y siempre con una preocupaci\u00f3n muy grande porque condiciona la vida de todos los Ciudadanos\u201d manifest\u00f3 Mario S\u00e1nchez.<\/p>\n\n\n\n<p>Este s\u00e1bado se van a reunir diversos actores del Partido Juntos Somos R\u00edo Negro en Choele-Choel donde se definir\u00e1 la Pol\u00edtica de alianza y cuestiones que tienen que ver con el funcionamiento org\u00e1nico del partido como la incorporaci\u00f3n de reuniones virtuales.<\/p>\n\n\n\n<p>Mario S\u00e1nchez destac\u00f3 que <strong>\u201cDebemos tener la voluntad de representar nuestro espacio en el lugar que nos toque ocupar y eso es algo que la mayor\u00eda de los militantes tenemos incorporados desde el momento que empezamos a trabajar\u201d <\/strong>y agreg\u00f3<strong> \u201csiempre entend\u00ed la pol\u00edtica como una herramienta para cambiar la realidad y una manera de&nbsp; trabajar por nuestra comunidad, pensando a la pol\u00edtica como un servicio p\u00fablico\u201d.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c84042b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c84042b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34b25a7\" data-id=\"34b25a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63b2ab3 elementor-widget elementor-widget-image\" data-id=\"63b2ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"437\" src=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-09-at-10.02.30-PM-1.jpeg\" class=\"attachment-large size-large wp-image-1749\" alt=\"\" srcset=\"https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-09-at-10.02.30-PM-1.jpeg 720w, https:\/\/www.elpolitologoyelpolitico.com.ar\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-09-at-10.02.30-PM-1-300x205.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/04\/10\/siempre-entendi-la-politica-como-una-herramienta-para-cambiar-la-realidad\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Desde la Secretaria de Desarrollo Social de la Ciudad de Viedma se viene trabajando con distintos programas para la poblaci\u00f3n. Mario S\u00e1nchez, Secretario de Desarrollo Social, mencion\u00f3 que el trabajo llevado a cabo durante el a\u00f1o pasado permiti\u00f3 conocer la condici\u00f3n de la Ciudad y abordar distintas acciones por la segunda ola del Covid-19. \u201cNosotros [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actores-politicos"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/1732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=1732"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/1732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/1733"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=1732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=1732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=1732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}