{"id":1590,"date":"2021-04-06T22:14:37","date_gmt":"2021-04-06T22:14:37","guid":{"rendered":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/?p=1590"},"modified":"2021-04-06T22:15:27","modified_gmt":"2021-04-06T22:15:27","slug":"lo-mejor-esta-por-venir","status":"publish","type":"post","link":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/04\/06\/lo-mejor-esta-por-venir\/","title":{"rendered":"\u201cLo mejor est\u00e1 por venir\u201d"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1590\" class=\"elementor elementor-1590\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c84db52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c84db52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79660c1\" data-id=\"79660c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6934a418 elementor-widget elementor-widget-text-editor\" data-id=\"6934a418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>Yamil Direne, participa de la pol\u00edtica hace varios a\u00f1os y cumpli\u00f3 ciertas funciones en el Estado Provincial y Municipal. Trabajo en los programas alimentarios de asistencia directa durante el Gobierno de Massaccesi (1987-1995), fue sub- secretario, ex presidente del tren patag\u00f3nico y hoy es uno de los candidatos a presidir la Uni\u00f3n C\u00edvica Radical en la Provincia de R\u00edo Negro.<\/p>\n\n\n\n<p>El ex intendente se encuentra trabajando en toda la Provincia con los afiliados quienes presentan un gran inter\u00e9s por emprender la tarea de recuperar el partido <strong>\u201caunque la tarea no es sencilla no perdemos las esperanzas\u201d <\/strong>expres\u00f3 Direne.<\/p>\n\n\n\n<p>Las elecciones internas llevadas a cabo en la Provincia de Buenos Aires y C\u00f3rdoba&nbsp; tuvieron un resultado muy positivo para la UCR, esperan que en Rio Negro exista la misma participaci\u00f3n.<\/p>\n\n\n\n<p><strong>\u201cPretendemos desde el partido poder recuperarlo, ponerlo en valor, abrir las afiliaciones para todos, hoy no contamos con una padr\u00f3n de juventud y la mayor\u00eda somos personas mayores, pero esto lo queremos cambiar\u201d<\/strong> declar\u00f3 Direne<\/p>\n\n\n\n<p>Desde el partido se busca el contacto con la sociedad que tanto fortaleci\u00f3 al radicalismo durante a\u00f1os, mediante un dialogo permanente trabajando en todas las problem\u00e1ticas sociales <strong>&nbsp;\u201cTenemos para rescatar que fuimos quienes armamos la Provincia, hoy actualmente necesitamos sentarnos con los afiliados para ver cosas que nosotros nos vimos\u201d <\/strong>aseguro el ex intendente.<\/p>\n\n\n\n<p>\u201c<strong>Nosotros tenemos un slogan que es, lo mejor est\u00e1 por venir, es por ello que creemos que este&nbsp; 11 de abril para nosotros comienza la recuperaci\u00f3n de la UCR para ponerla en valor y que ocupe el lugar que tiene que ocupar\u201d <\/strong>afirm\u00f3 el candidato a presidir la UCR en R\u00edo Negro.<\/p>\n\n\n\n<p>Las elecciones internas se llevaran a cabo el 11 del corriente mes, el proceso electoral est\u00e1 previsto por la junta electoral provincial, junto con la dirigencia del comit\u00e9 a cargo de Lorena Matzen. Adem\u00e1s se elegir\u00e1n representantes de Rio Negro para la mesa Nacional y la Convenci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/2021\/04\/06\/lo-mejor-esta-por-venir\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Yamil Direne, participa de la pol\u00edtica hace varios a\u00f1os y cumpli\u00f3 ciertas funciones en el Estado Provincial y Municipal. Trabajo en los programas alimentarios de asistencia directa durante el Gobierno de Massaccesi (1987-1995), fue sub- secretario, ex presidente del tren patag\u00f3nico y hoy es uno de los candidatos a presidir la Uni\u00f3n C\u00edvica Radical en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actores-politicos"],"_links":{"self":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/1590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=1590"}],"version-history":[{"count":0,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/1590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/1591"}],"wp:attachment":[{"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=1590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=1590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elpolitologoyelpolitico.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=1590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}